{"id":10889,"date":"2018-01-17T13:15:20","date_gmt":"2018-01-17T13:15:20","guid":{"rendered":"http:\/\/dev.quantumvitalitygroup.com\/?page_id=1376"},"modified":"2022-08-29T07:06:39","modified_gmt":"2022-08-29T07:06:39","slug":"product-claims-health-disclaimer","status":"publish","type":"page","link":"http:\/\/165.227.165.113\/de\/product-claims-health-disclaimer\/","title":{"rendered":"Product Claims &#038; Health Disclaimer"},"content":{"rendered":"<p>[vc_row][vc_column]<div id=\"ultimate-heading-99036a5708a42afea\" class=\"uvc-heading ult-adjust-bottom-margin ultimate-heading-99036a5708a42afea uvc-1307 \" data-hspacer=\"no_spacer\"  data-halign=\"left\" style=\"text-align:left\"><div class=\"uvc-heading-spacer no_spacer\" style=\"top\"><\/div><div class=\"uvc-main-heading ult-responsive\"  data-ultimate-target='.uvc-heading.ultimate-heading-99036a5708a42afea h1'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}' ><h1 style=\"font-weight:normal;margin-top:35px;margin-bottom:35px;\">Produktanspr\u00fcche und Gesundheitshinweise<\/h1><\/div><\/div>[vc_column_text]<\/p>\n<p class=\"p1\">Das Unternehmen macht keine medizinischen Behauptungen und behauptet oder impliziert nicht, dass ein Produkt vom Unternehmen oder einer Regulierungsbeh\u00f6rde formuliert, entwickelt oder genehmigt wurde, um eine Krankheit oder einen Gesundheitszustand zu diagnostizieren, zu behandeln, zu heilen oder zu verhindern. Dies w\u00fcrde f\u00e4lschlicherweise implizieren, dass es sich bei den Produkten um Medikamente und nicht um Kosmetika, Hautpflege oder Nahrungserg\u00e4nzungsmittel handelt.<\/p>\n<p class=\"p1\">Das Unternehmen vergleicht niemals Produkte mit Arzneimitteln. Jegliche derartige Darstellungen, Anspr\u00fcche oder Vergleiche durch Sie k\u00f6nnen zu Ihrer pers\u00f6nlichen Haftung f\u00fchren.<\/p>\n<p class=\"p1\"><strong><span class=\"s2\">Produktanspr\u00fcche &amp; Gesundheit:<\/span><\/strong><\/p>\n<p class=\"p1\"><strong>Bitte beachten Sie, dass die Produkte und Behauptungen auf dieser Webseite und auf den mit ihr verbundenen Webseiten des Unternehmens nicht von offiziellen Institutionen bewertet wurden und nicht zur Diagnose, Vorbeugung, Behandlung oder Heilung einer Krankheit oder eines Leidens bestimmt sind. Das Unternehmen und seine Webseiten beabsichtigen nicht, medizinische Beratung anzubieten. <\/strong><\/p>\n<p class=\"p1\"><strong>Die Produkte, Beschreibungen, Forschungen usw. auf dieser Webseite dienen nur zu Informationszwecken. Informationen \u00fcber Gesundheit und medizinische Bedingungen, Produkte und Ratschl\u00e4ge auf dieser oder anderen verlinkten Webseiten sind kein Ersatz f\u00fcr die Meinung von Gesundheitsexperten.<\/strong><\/p>\n<p class=\"p1\">Bitte konsultieren Sie einen Arzt oder andere Fachleute des Gesundheitswesens bez\u00fcglich aller medizinischen, gesundheitsbezogenen Fragen zur Diagnose und Behandlung. Ein Selbstmanagement unter Ber\u00fccksichtigung der pers\u00f6nlichen Gesundheit wird nicht empfohlen.<\/p>\n<p class=\"p1\">Bevor Sie ein Produkt verwenden, sollten Sie dessen Etiketten und Verpackung sorgf\u00e4ltig lesen.<\/p>\n<p class=\"p1\">Vor der ersten Einnahme unseres Produktes sollten Sie sich mit Ihrem Arzt oder einer anderen medizinischen Fachkraft in Verbindung setzen. Sie sollten Ihren Arzt zu jeder Wechselwirkung mit bereits verwendeten Medikamenten oder Nahrungserg\u00e4nzungsmitteln befragen.<\/p>\n<p class=\"p1\">Kommentare auf dieser Webseite, auf verlinkten Seiten, in Foren und anderen schriftlichen oder m\u00fcndlichen Mitteilungen sind keine Behauptungen von <span class=\"s2\">Wetality <\/span> und stellen nur pers\u00f6nliche Meinungen dar.<\/p>\n<p class=\"p1\">Die <span class=\"s2\">Wetality <\/span>haftet nicht f\u00fcr Informationen \u00fcber Gesundheitsfragen und kann nicht f\u00fcr Sch\u00e4den, die sich aus den Informationen ergeben, verantwortlich gemacht werden.<\/p>\n<p class=\"p1\">Das Unternehmen erkl\u00e4rt oder impliziert nicht, dass ein Produkt von nationalen Beh\u00f6rden registriert oder genehmigt ist. Es ist die Verpflichtung des Unternehmens, sicherzustellen, dass alle Produkte, die in einem bestimmten zugelassenen Land zum Verkauf zugelassen sind, alle Anforderungen und Standards dieses zugelassenen Gebiets erf\u00fcllen.<\/p>\n<p class=\"p1\">Einige M\u00e4rkte erfordern keine Vorabanmeldung, w\u00e4hrend andere eine spezifische Produktanmeldung f\u00fcr die einzelnen kosmetischen oder ern\u00e4hrungsphysiologischen Produkte, die das Unternehmen verkauft, erfordern.<\/p>\n<p class=\"p1\">Beachten Sie bei der Angabe von Produktvorteilen oder pers\u00f6nlichen Aussagen zu Produkten, dass es sich immer nur um Ihre pers\u00f6nliche Erfahrung und Meinung handelt. Spezifische gesundheitsbezogene Angaben k\u00f6nnen nur in \u00dcbereinstimmung mit der nationalen Gesetzgebung zu n\u00e4hrwert- und gesundheitsbezogenen Angaben gemacht werden.<\/p>\n<p class=\"p1\">Die Behauptungen m\u00fcssen korrekt und nicht irref\u00fchrend sein. Wenn Sie die Webseiten des Unternehmens nutzen, einen Vertrag einreichen und Gesch\u00e4fte bez\u00fcglich der Produkte des Unternehmens t\u00e4tigen, best\u00e4tigen Sie damit auch, dass Sie die Richtlinien des Unternehmens zum Haftungsausschluss kennen. Es ist von gro\u00dfer Bedeutung, sie vollst\u00e4ndig zu verstehen und sich entsprechend zu verhalten.<\/p>\n<div id=\"gtx-trans\" style=\"position: absolute; left: 503px; top: 1067.89px;\">\n<div class=\"gtx-trans-icon\"><\/div>\n<\/div>\n<p>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text] Das Unternehmen macht keine medizinischen Behauptungen und behauptet oder impliziert nicht, dass ein Produkt vom Unternehmen oder einer Regulierungsbeh\u00f6rde formuliert, entwickelt oder genehmigt wurde, um eine Krankheit oder einen Gesundheitszustand zu diagnostizieren, zu behandeln, zu heilen oder zu verhindern. Dies w\u00fcrde f\u00e4lschlicherweise implizieren, dass es sich bei den Produkten um Medikamente und nicht um [&hellip;]<\/p>\n","protected":false},"author":6865,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"templates\/template-default-no-sidebar.php","meta":{"footnotes":""},"acf":[],"_links":{"self":[{"href":"http:\/\/165.227.165.113\/de\/wp-json\/wp\/v2\/pages\/10889"}],"collection":[{"href":"http:\/\/165.227.165.113\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/165.227.165.113\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/165.227.165.113\/de\/wp-json\/wp\/v2\/users\/6865"}],"replies":[{"embeddable":true,"href":"http:\/\/165.227.165.113\/de\/wp-json\/wp\/v2\/comments?post=10889"}],"version-history":[{"count":2,"href":"http:\/\/165.227.165.113\/de\/wp-json\/wp\/v2\/pages\/10889\/revisions"}],"predecessor-version":[{"id":97128,"href":"http:\/\/165.227.165.113\/de\/wp-json\/wp\/v2\/pages\/10889\/revisions\/97128"}],"wp:attachment":[{"href":"http:\/\/165.227.165.113\/de\/wp-json\/wp\/v2\/media?parent=10889"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}